{"id":1889,"date":"2017-09-20T13:30:52","date_gmt":"2017-09-20T11:30:52","guid":{"rendered":"https:\/\/www.ch-open.ch\/?p=1889"},"modified":"2017-09-20T13:32:06","modified_gmt":"2017-09-20T11:32:06","slug":"dinacon-awards-2017-die-nominierten-sind-bekannt","status":"publish","type":"post","link":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/","title":{"rendered":"DINAcon Awards 2017: Die Nominierten sind bekannt"},"content":{"rendered":"<p>Bern, 20. September 2017<\/p>\n<p><strong>Die DINAcon Awards werden heute in einem Monat im Rahmen der ersten DINAcon am 20. Oktober 2017 an digital nachhaltige Projekte und Organisationen vergeben. Sie zeichnen den Mut und die Innovationskraft von Firmen, Beh\u00f6rden, Communities, Entwicklern und Einzelpersonen aus. Nun sind die 26 Nominierten bekannt.<\/strong><\/p>\n<p>Die Projekteingaben repr\u00e4sentieren das ganze Spektrum der digitalen Nachhaltigkeit: Von klassischen Open Source Softwareprojekten wie der freien und dezentralen Dropbox Alternative Nextcloud, Open Data Anwendungen wie der Offline-Medizindatenbank f\u00fcr Entwicklungsl\u00e4nder Wikimed, Open Source Anwendungen im Unternehmensumfeld wie der Schweizer Containerplattform APPUiO bis zur offenen IoT Plattform der Open Network Infrastructure Association. Die vollst\u00e4ndige Liste der 26 nominierten Projekte und Organisationen finden sind hier zu finden: <a href=\"https:\/\/dinacon.ch\/nominationen\/\" target=\"_blank\" rel=\"noopener\">https:\/\/dinacon.ch\/nominationen\/<\/a><\/p>\n<p>Neuer Name tr\u00e4gt Entwicklungen im Bereich Open Data Rechnung<br \/>\nBisher wurde die Preisverleihung unter dem Namen CH Open Source Awards gef\u00fchrt. Mit dem neuen Namen DINAcon Awards wollen der Veranstalter der Entwicklung im Bereich Open Data und digitaler Nachhaltigkeit Rechnung tragen und das Spektrum der Preisverleihung erweitern. Eine Jury von ausgewiesenen Experten und Unternehmern \u00fcbernahm die Nominierung und die Auswahl der Preistr\u00e4ger der DINAcon Awards 2017. Die Preisverleihung findet heute in einem Monat am Freitag, 20. Oktober 2017 im Rahmen der DINAcon 2017 statt: <a href=\"https:\/\/dinacon.ch\/programm\/\" target=\"_blank\" rel=\"noopener\">https:\/\/dinacon.ch\/programm\/<br \/>\n<\/a>Die letztj\u00e4hrigen sechs CH Open Source Awards wurden an die Open Source CRM-L\u00f6sung SuiteCRM, die Post CH AG f\u00fcr ihre MariaDB-Migration, an Florian Bruhin mit qutebrowser, an Ren\u00e9 Moser mit Ansible CloudStack, an die Open Data Portale opendata.swiss und data.sbb.ch vergeben.<\/p>\n<p>Erste Konferenz f\u00fcr digitale Nachhaltigkeit<br \/>\nDie DINAcon wird von der Forschungsstelle Digitale Nachhaltigkeit der Universit\u00e4t Bern in Zusammenarbeit mit der Parlamentarischen Gruppe Digitale Nachhaltigkeit (Parldigi) und mehreren Verb\u00e4nden (Opendata.ch, CH Open, tcbe.ch etc.) im Welle7 Workspace beim Bahnhof Bern organisiert. Erwartet werden \u00fcber 200 Entscheidungstr\u00e4ger und Opinion Leader aus Politik, Wirtschaft, \u00f6ffentlichem Sektor und der Digitalisierungs-Szene. Im Plenum werden unter anderem Bibi Bleekemolen, Mitgr\u00fcnderin von Fairphone, sowie die Nationalr\u00e4te Balthasar Gl\u00e4ttli, Franz Gr\u00fcter und Kathy Riklin referieren.<br \/>\nIn den \u00fcber 20 Sessions zu Open Source, Open Data, Blockchain und vielen weiteren Gebieten werden Fachleute vertiefte Einblicke in aktuelle Themen der digitalen Nachhaltigkeit bieten. Unterst\u00fctzt wird die Konferenz durch den Welle7 Workspace als Location Sponsor, die Haslerstiftung sowie den Firmensponsoren Snowflake, Puzzle, ewb, APP, Avintis, seantis, ICG , Liip und why! open computing. Das aktuelle Programm ist zu finden unter: <a href=\"https:\/\/dinacon.ch\/programm\/\" target=\"_blank\" rel=\"noopener\">https:\/\/dinacon.ch\/programm\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bern, 20. September 2017 Die DINAcon Awards werden heute in einem Monat im Rahmen der ersten DINAcon am 20. Oktober 2017 an digital nachhaltige Projekte und Organisationen vergeben. Sie zeichnen den Mut und die Innovationskraft von Firmen, Beh\u00f6rden, Communities, Entwicklern und Einzelpersonen aus. Nun sind die 26 Nominierten bekannt. Die Projekteingaben repr\u00e4sentieren das ganze Spektrum&hellip;<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-1889","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DINAcon Awards 2017: Die Nominierten sind bekannt &#060; CH Open<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DINAcon Awards 2017: Die Nominierten sind bekannt\" \/>\n<meta property=\"og:description\" content=\"Bern, 20. September 2017 Die DINAcon Awards werden heute in einem Monat im Rahmen der ersten DINAcon am 20. Oktober 2017 an digital nachhaltige Projekte und Organisationen vergeben. Sie zeichnen den Mut und die Innovationskraft von Firmen, Beh\u00f6rden, Communities, Entwicklern und Einzelpersonen aus. Nun sind die 26 Nominierten bekannt. Die Projekteingaben repr\u00e4sentieren das ganze Spektrum&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/\" \/>\n<meta property=\"og:site_name\" content=\"CH Open\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-20T11:30:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-20T11:32:06+00:00\" \/>\n<meta name=\"author\" content=\"alexandrabarden\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ch_open\" \/>\n<meta name=\"twitter:site\" content=\"@ch_open\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexandrabarden\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/\"},\"author\":{\"name\":\"alexandrabarden\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/person\\\/78ff202deb177259d1aa898275f2da79\"},\"headline\":\"DINAcon Awards 2017: Die Nominierten sind bekannt\",\"datePublished\":\"2017-09-20T11:30:52+00:00\",\"dateModified\":\"2017-09-20T11:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/\"},\"wordCount\":408,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/\",\"name\":\"DINAcon Awards 2017: Die Nominierten sind bekannt &#060; CH Open\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#website\"},\"datePublished\":\"2017-09-20T11:30:52+00:00\",\"dateModified\":\"2017-09-20T11:32:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-awards-2017-die-nominierten-sind-bekannt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DINAcon Awards 2017: Die Nominierten sind bekannt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/\",\"name\":\"CH Open\",\"description\":\"Verein CH Open\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ch-open.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#organization\",\"name\":\"CH Open\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/CHOpen_Logo_700.png\",\"contentUrl\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/CHOpen_Logo_700.png\",\"width\":700,\"height\":256,\"caption\":\"CH Open\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ch_open\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/openexpo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/person\\\/78ff202deb177259d1aa898275f2da79\",\"name\":\"alexandrabarden\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g\",\"caption\":\"alexandrabarden\"},\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/author\\\/alexandrabarden\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DINAcon Awards 2017: Die Nominierten sind bekannt &#060; CH Open","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/","og_locale":"en_US","og_type":"article","og_title":"DINAcon Awards 2017: Die Nominierten sind bekannt","og_description":"Bern, 20. September 2017 Die DINAcon Awards werden heute in einem Monat im Rahmen der ersten DINAcon am 20. Oktober 2017 an digital nachhaltige Projekte und Organisationen vergeben. Sie zeichnen den Mut und die Innovationskraft von Firmen, Beh\u00f6rden, Communities, Entwicklern und Einzelpersonen aus. Nun sind die 26 Nominierten bekannt. Die Projekteingaben repr\u00e4sentieren das ganze Spektrum&hellip;","og_url":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/","og_site_name":"CH Open","article_published_time":"2017-09-20T11:30:52+00:00","article_modified_time":"2017-09-20T11:32:06+00:00","author":"alexandrabarden","twitter_card":"summary_large_image","twitter_creator":"@ch_open","twitter_site":"@ch_open","twitter_misc":{"Written by":"alexandrabarden","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/#article","isPartOf":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/"},"author":{"name":"alexandrabarden","@id":"https:\/\/www.ch-open.ch\/#\/schema\/person\/78ff202deb177259d1aa898275f2da79"},"headline":"DINAcon Awards 2017: Die Nominierten sind bekannt","datePublished":"2017-09-20T11:30:52+00:00","dateModified":"2017-09-20T11:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/"},"wordCount":408,"publisher":{"@id":"https:\/\/www.ch-open.ch\/#organization"},"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/","url":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/","name":"DINAcon Awards 2017: Die Nominierten sind bekannt &#060; CH Open","isPartOf":{"@id":"https:\/\/www.ch-open.ch\/#website"},"datePublished":"2017-09-20T11:30:52+00:00","dateModified":"2017-09-20T11:32:06+00:00","breadcrumb":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-awards-2017-die-nominierten-sind-bekannt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ch-open.ch\/en\/"},{"@type":"ListItem","position":2,"name":"DINAcon Awards 2017: Die Nominierten sind bekannt"}]},{"@type":"WebSite","@id":"https:\/\/www.ch-open.ch\/#website","url":"https:\/\/www.ch-open.ch\/","name":"CH Open","description":"Verein CH Open","publisher":{"@id":"https:\/\/www.ch-open.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ch-open.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ch-open.ch\/#organization","name":"CH Open","url":"https:\/\/www.ch-open.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ch-open.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2017\/03\/CHOpen_Logo_700.png","contentUrl":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2017\/03\/CHOpen_Logo_700.png","width":700,"height":256,"caption":"CH Open"},"image":{"@id":"https:\/\/www.ch-open.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ch_open","https:\/\/www.youtube.com\/user\/openexpo"]},{"@type":"Person","@id":"https:\/\/www.ch-open.ch\/#\/schema\/person\/78ff202deb177259d1aa898275f2da79","name":"alexandrabarden","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g","caption":"alexandrabarden"},"url":"https:\/\/www.ch-open.ch\/en\/author\/alexandrabarden\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/posts\/1889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/comments?post=1889"}],"version-history":[{"count":3,"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/posts\/1889\/revisions"}],"predecessor-version":[{"id":1893,"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/posts\/1889\/revisions\/1893"}],"wp:attachment":[{"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/media?parent=1889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/categories?post=1889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ch-open.ch\/en\/wp-json\/wp\/v2\/tags?post=1889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}