{"id":4350,"date":"2019-10-28T10:19:27","date_gmt":"2019-10-28T09:19:27","guid":{"rendered":"https:\/\/www.ch-open.ch\/?p=4350"},"modified":"2019-10-28T10:20:21","modified_gmt":"2019-10-28T09:20:21","slug":"dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019","status":"publish","type":"post","link":"https:\/\/www.ch-open.ch\/fr\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/","title":{"rendered":"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019"},"content":{"rendered":"\n<p><strong>\u00dcber 200 Teilnehmende haben heute an der DINAcon 2019 den vier Keynotes gespannt zugeh\u00f6rt: Katariina Kari, Ontologin bei Zalando; Bart van Leeuwen, Software Engineer bei Netage und Feuerwehrmann; Julia Kloiber, digitale Gr\u00fcnderin Prototype Fund und Code for Germany sowie Peter Ganten, Gr\u00fcnder Univention und Pr\u00e4sident der Open Source Business Alliance. Als H\u00f6hepunkt wurden die diesj\u00e4hrigen DINAcon Awards an f\u00fcnf herausragende Projekte und Akteure vergeben: Open School Maps, Umweltrating, den Kanton Bern, Caluma und Zammad.<\/strong><\/p>\n<p>An der heutigen DINAcon wurden die verschiedensten Facetten der digitalen Nachhaltigkeit sichtbar. Zum ersten Mal fand ausserdem in diesem Rahmen das Knowledge Graph Forum statt, an der die Potenziale von verlinkten Daten durchleuchtet wurden.<\/p>\n<p>Im Plenum begeisterte Katariina Kari, Ontologin (=Datenarchitektin) beim Zalando Tech Hub in Helsinki, das Publikum mit anschaulichen Beispielen der Funktionsweise von Wissensgraphen in der Fashion-Welt. Einen weiteren Anwendungsbereich f\u00fcr smart verlinkte Daten zeigte Bart van Leeuwen, Feuerwehrmann und Software Engineer. Dem&nbsp; Publikum gew\u00e4hrten die beiden Referierenden am Nachmittag einen Blick in die Zukunft von Open Source Software und digitaler Souver\u00e4nit\u00e4t. Julia Kloiber, Gr\u00fcnderin vom Prototype Fund und Code for Germany, ging auf das Potenzial und die Herausforderungen von Open Source in Civic Tech Projekten ein. Peter Ganten, Gr\u00fcnder von Univention und Pr\u00e4sident der Open Source Business Alliance&nbsp; veranschaulichte unsere technologische Abh\u00e4ngigkeit mit historischen Analogien ins Mittelalter. Neben Linked Data und Open Source Software wurden in den 12 Sessions auch weitere Themen wie E-ID,&nbsp; Open Data, OpenStreetMap, Smart City und Artificial Intelligence vertieft.<\/p>\n<p>Als H\u00f6hepunkt des Tages wurden am Nachmittag die DINAcon Awards 2019 vergeben. Von den 41 Eingaben wurden f\u00fcnf besonders herausragende Projekte von der Fachjury ausgew\u00e4hlt. Gewinner des Open Source Project Awards ist das Open Source Helpdesk System <a href=\"https:\/\/zammad.com\/de\">Zammad<\/a> \u2013 und ist damit ausserdem f\u00fcr den Digital Economy Award von swissICT nominiert. Mit dem Best Newcomer Award wurde <a href=\"https:\/\/caluma.io\">Caluma<\/a> ausgezeichnet, das Open Source Formular und Workflow Builder. Der <a href=\"https:\/\/github.com\/kanton-bern\">Kanton Bern<\/a> erhielt f\u00fcr den zentralen Service zur Publikation von Open Source Software aus der Verwaltung den Best Practice Award. Der Open Data Award ging an das <a href=\"https:\/\/ecorating.ch\/de\">Umweltrating<\/a>. Und der Open Education Award wurde an <a href=\"https:\/\/openschoolmaps.ch\">OpenSchoolMaps<\/a> \u00fcberreicht, Lehr- und Lernmaterialien \u00fcber offene Karten und Kartendaten f\u00fcr Selbstlerner und Lehrpersonen.<\/p>\n<p>Die DINAcon wird von der Forschungsstelle Digitale Nachhaltigkeit der Universit\u00e4t Bern in Zusammenarbeit mit CH Open, Opendata.ch, Digital Impact Network, imito AG, und der Parlamentarischen Gruppe Digitale Nachhaltigkeit (Parldigi) organisiert. Erm\u00f6glicht wird sie durch die Sponsoren: Welle7 Workspace, BEKB, Haslerstiftung, Onebus, Puzzle ICT, it-novum, Red Hat, SUSE, iqual, App Unternehmensberatung, SBB, Seantis und 4teamwork.<\/p>\n<p>Website mit weiteren Informationen: <a href=\"http:\/\/www.dinacon.ch\">www.dinacon.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber 200 Teilnehmende haben heute an der DINAcon 2019 den vier Keynotes gespannt zugeh\u00f6rt: Katariina Kari, Ontologin bei Zalando; Bart van Leeuwen, Software Engineer bei Netage und Feuerwehrmann; Julia Kloiber, digitale Gr\u00fcnderin Prototype Fund und Code for Germany sowie Peter Ganten, Gr\u00fcnder Univention und Pr\u00e4sident der Open Source Business Alliance. Als H\u00f6hepunkt wurden die diesj\u00e4hrigen&hellip;<\/p>\n","protected":false},"author":14,"featured_media":2632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[41,31],"tags":[],"class_list":["post-4350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019 &#060; CH Open<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019\" \/>\n<meta property=\"og:description\" content=\"\u00dcber 200 Teilnehmende haben heute an der DINAcon 2019 den vier Keynotes gespannt zugeh\u00f6rt: Katariina Kari, Ontologin bei Zalando; Bart van Leeuwen, Software Engineer bei Netage und Feuerwehrmann; Julia Kloiber, digitale Gr\u00fcnderin Prototype Fund und Code for Germany sowie Peter Ganten, Gr\u00fcnder Univention und Pr\u00e4sident der Open Source Business Alliance. Als H\u00f6hepunkt wurden die diesj\u00e4hrigen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"CH Open\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-28T09:19:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-28T09:20:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2018\/06\/DINAcon-horizontal-halbgeschnitten.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1289\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"alexandrabarden\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ch_open\" \/>\n<meta name=\"twitter:site\" content=\"@ch_open\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexandrabarden\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/\"},\"author\":{\"name\":\"alexandrabarden\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/person\\\/78ff202deb177259d1aa898275f2da79\"},\"headline\":\"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019\",\"datePublished\":\"2019-10-28T09:19:27+00:00\",\"dateModified\":\"2019-10-28T09:20:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/DINAcon-horizontal-halbgeschnitten.png\",\"articleSection\":[\"Allgemein\",\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/\",\"name\":\"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019 &#060; CH Open\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/DINAcon-horizontal-halbgeschnitten.png\",\"datePublished\":\"2019-10-28T09:19:27+00:00\",\"dateModified\":\"2019-10-28T09:20:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/DINAcon-horizontal-halbgeschnitten.png\",\"contentUrl\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/DINAcon-horizontal-halbgeschnitten.png\",\"width\":1289,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/en\\\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ch-open.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/\",\"name\":\"CH Open\",\"description\":\"Verein CH Open\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ch-open.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#organization\",\"name\":\"CH Open\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/CHOpen_Logo_700.png\",\"contentUrl\":\"https:\\\/\\\/www.ch-open.ch\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/CHOpen_Logo_700.png\",\"width\":700,\"height\":256,\"caption\":\"CH Open\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ch_open\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/openexpo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ch-open.ch\\\/#\\\/schema\\\/person\\\/78ff202deb177259d1aa898275f2da79\",\"name\":\"alexandrabarden\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g\",\"caption\":\"alexandrabarden\"},\"url\":\"https:\\\/\\\/www.ch-open.ch\\\/fr\\\/author\\\/alexandrabarden\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019 &#060; CH Open","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/","og_locale":"fr_FR","og_type":"article","og_title":"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019","og_description":"\u00dcber 200 Teilnehmende haben heute an der DINAcon 2019 den vier Keynotes gespannt zugeh\u00f6rt: Katariina Kari, Ontologin bei Zalando; Bart van Leeuwen, Software Engineer bei Netage und Feuerwehrmann; Julia Kloiber, digitale Gr\u00fcnderin Prototype Fund und Code for Germany sowie Peter Ganten, Gr\u00fcnder Univention und Pr\u00e4sident der Open Source Business Alliance. Als H\u00f6hepunkt wurden die diesj\u00e4hrigen&hellip;","og_url":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/","og_site_name":"CH Open","article_published_time":"2019-10-28T09:19:27+00:00","article_modified_time":"2019-10-28T09:20:21+00:00","og_image":[{"width":1289,"height":354,"url":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2018\/06\/DINAcon-horizontal-halbgeschnitten.png","type":"image\/png"}],"author":"alexandrabarden","twitter_card":"summary_large_image","twitter_creator":"@ch_open","twitter_site":"@ch_open","twitter_misc":{"\u00c9crit par":"alexandrabarden","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#article","isPartOf":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/"},"author":{"name":"alexandrabarden","@id":"https:\/\/www.ch-open.ch\/#\/schema\/person\/78ff202deb177259d1aa898275f2da79"},"headline":"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019","datePublished":"2019-10-28T09:19:27+00:00","dateModified":"2019-10-28T09:20:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/"},"wordCount":444,"publisher":{"@id":"https:\/\/www.ch-open.ch\/#organization"},"image":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2018\/06\/DINAcon-horizontal-halbgeschnitten.png","articleSection":["Allgemein","News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/","url":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/","name":"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019 &#060; CH Open","isPartOf":{"@id":"https:\/\/www.ch-open.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2018\/06\/DINAcon-horizontal-halbgeschnitten.png","datePublished":"2019-10-28T09:19:27+00:00","dateModified":"2019-10-28T09:20:21+00:00","breadcrumb":{"@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#primaryimage","url":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2018\/06\/DINAcon-horizontal-halbgeschnitten.png","contentUrl":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2018\/06\/DINAcon-horizontal-halbgeschnitten.png","width":1289,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/www.ch-open.ch\/en\/dinacon-begeistert-200-teilnehmende-und-die-award-gewinner-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ch-open.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"DINAcon begeistert 200 Teilnehmende und die Award-Gewinner 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.ch-open.ch\/#website","url":"https:\/\/www.ch-open.ch\/","name":"CH Open","description":"Verein CH Open","publisher":{"@id":"https:\/\/www.ch-open.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ch-open.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ch-open.ch\/#organization","name":"CH Open","url":"https:\/\/www.ch-open.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ch-open.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2017\/03\/CHOpen_Logo_700.png","contentUrl":"https:\/\/www.ch-open.ch\/wp-content\/uploads\/2017\/03\/CHOpen_Logo_700.png","width":700,"height":256,"caption":"CH Open"},"image":{"@id":"https:\/\/www.ch-open.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ch_open","https:\/\/www.youtube.com\/user\/openexpo"]},{"@type":"Person","@id":"https:\/\/www.ch-open.ch\/#\/schema\/person\/78ff202deb177259d1aa898275f2da79","name":"alexandrabarden","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a5422c0fb22e60fc76df118795f44c8e127eab30f6f6cef9b2fabb84003752d?s=96&d=mm&r=g","caption":"alexandrabarden"},"url":"https:\/\/www.ch-open.ch\/fr\/author\/alexandrabarden\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/posts\/4350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/comments?post=4350"}],"version-history":[{"count":3,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/posts\/4350\/revisions"}],"predecessor-version":[{"id":4353,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/posts\/4350\/revisions\/4353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/media\/2632"}],"wp:attachment":[{"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/media?parent=4350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/categories?post=4350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ch-open.ch\/fr\/wp-json\/wp\/v2\/tags?post=4350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}